{"id":213,"date":"2015-11-20T12:00:21","date_gmt":"2015-11-20T11:00:21","guid":{"rendered":"https:\/\/www.wildmagegames.com\/fr_FR\/?p=213"},"modified":"2017-07-08T19:21:13","modified_gmt":"2017-07-08T17:21:13","slug":"annonce-de-mon-jeu-almost-epic-adventures-the-goblins-week","status":"publish","type":"post","link":"https:\/\/www.wildmagegames.com\/fr\/2015\/11\/20\/annonce-de-mon-jeu-almost-epic-adventures-the-goblins-week\/","title":{"rendered":"Annonce de mon jeu : Almost Epic Adventures &#8211; The Goblin&rsquo;s Week !"},"content":{"rendered":"<p><a href=\"https:\/\/www.wildmagegames.com\/wp-content\/uploads\/2016\/01\/logo-e1483606956701.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-826\" src=\"https:\/\/www.wildmagegames.com\/wp-content\/uploads\/2016\/01\/logo-e1483606956701.png\" alt=\"\" width=\"840\" height=\"197\" \/><\/a><\/p>\n<p>Apr\u00e8s des mois de travail acharn\u00e9, je suis fier de vous annoncer que la page de pr\u00e9sentation de mon jeu est enfin disponible ! D\u00e9couvrez l\u00e0 <a href=\"https:\/\/www.wildmagegames.com\/fr_FR\/goblin\/\">ICI<\/a> !<\/p>\n<h3>Partagez la page<\/h3>\n<p>Si vous aimez le concept du jeu, surtout n&rsquo;h\u00e9sitez pas \u00e0 partager la page, parlez-en autour de vous, afin de le faire conna\u00eetre au plus de monde possible ! Merci !<\/p>\n<h3>Donnez moi votre avis<\/h3>\n<p>Dites moi ce que vous pensez du jeu et de la page. Est-ce que la page et le concept sont assez attrayants ? Avez vous des probl\u00e8mes techniques ou d&rsquo;affichage ? Avez vous des suggestions ?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s des mois de travail acharn\u00e9, je suis fier de vous annoncer que la page de pr\u00e9sentation de mon jeu est enfin disponible ! D\u00e9couvrez l\u00e0 ICI ! Partagez la page Si vous aimez le concept du jeu, surtout n&rsquo;h\u00e9sitez pas \u00e0 partager la page, parlez-en autour de vous, afin de le faire conna\u00eetre au [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":405,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.wildmagegames.com\/fr\/wp-json\/wp\/v2\/posts\/213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wildmagegames.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wildmagegames.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wildmagegames.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wildmagegames.com\/fr\/wp-json\/wp\/v2\/comments?post=213"}],"version-history":[{"count":3,"href":"https:\/\/www.wildmagegames.com\/fr\/wp-json\/wp\/v2\/posts\/213\/revisions"}],"predecessor-version":[{"id":455,"href":"https:\/\/www.wildmagegames.com\/fr\/wp-json\/wp\/v2\/posts\/213\/revisions\/455"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wildmagegames.com\/fr\/wp-json\/wp\/v2\/media\/405"}],"wp:attachment":[{"href":"https:\/\/www.wildmagegames.com\/fr\/wp-json\/wp\/v2\/media?parent=213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wildmagegames.com\/fr\/wp-json\/wp\/v2\/categories?post=213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wildmagegames.com\/fr\/wp-json\/wp\/v2\/tags?post=213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}